{"id":31045,"date":"2025-12-26T10:29:47","date_gmt":"2025-12-26T09:29:47","guid":{"rendered":"https:\/\/desto.life\/property\/can-agustin\/"},"modified":"2026-01-27T15:27:13","modified_gmt":"2026-01-27T14:27:13","slug":"can-agustin","status":"publish","type":"property","link":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/","title":{"rendered":"Can Agust\u00edn"},"content":{"rendered":"<p>Villa San Agust\u00edn es una propiedad recientemente renovada, ubicada en las tranquilas colinas de San Agust\u00edn, que ofrece total privacidad e impresionantes vistas panor\u00e1micas del paisaje verde, las monta\u00f1as y una vista lateral al mar. La villa cuenta con 259 m\u00b2 de espacio habitable en una parcela de 2.034 m\u00b2, con cuatro dormitorios, cuatro ba\u00f1os y una piscina privada rodeada de tranquilas zonas al aire libre. Est\u00e1 equipada con aire acondicionado, calefacci\u00f3n por suelo radiante, una estufa de le\u00f1a, paneles solares, un sistema de alarma y una cochera. A pocos minutos se encuentran Cala Bassa, Cala Conta y Cala Tarida, as\u00ed como los pueblos de San Agust\u00edn y San Jos\u00e9. La ciudad de Ibiza est\u00e1 a solo 20 minutos en coche.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villa San Agust\u00edn es una propiedad recientemente renovada, ubicada en las tranquilas colinas de San Agust\u00edn, que ofrece total privacidad e impresionantes vistas panor\u00e1micas del paisaje verde, las monta\u00f1as y una vista lateral al mar. La villa cuenta con 259 m\u00b2 de espacio habitable en una parcela de 2.034 m\u00b2, con cuatro dormitorios, cuatro ba\u00f1os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31047,"parent":0,"menu_order":0,"template":"","property_type":[],"property_status":[],"property_feature":[],"property_label":[],"property_country":[],"property_area":[],"class_list":["post-31045","property","type-property","status-publish","has-post-thumbnail","hentry"],"property_meta":{"fave_featured":["0"],"houzez_featured_listing_date":[""],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["31047"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["123"],"fave_property_price":["2950000"],"fave_property_size":["259 m\u00b2"],"fave_property_land":["2034 m\u00b2"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["4"],"fave_loggedintoview":["1"],"fave_features":["<ul>\n<li>4 refinadas suites de dormitorio, cada una de ellas con privacidad y vistas tranquilas<\/li>\n<li>4 ba\u00f1os modernos con acabados de calidad<\/li>\n<li>Luminosas zonas de estar que combinan el confort contempor\u00e1neo con el car\u00e1cter natural ibicenco<\/li>\n<li>Piscina privada, terrazas para tomar el sol y m\u00faltiples espacios de descanso al aire libre<\/li>\n<li>Jard\u00edn mediterr\u00e1neo con zonas verdes rodeado de bosque y naturaleza<\/li>\n<li>Vistas panor\u00e1micas de exuberantes colinas verdes, monta\u00f1as y una vista lateral al mar<\/li>\n<li>Aire acondicionado, calefacci\u00f3n por suelo radiante, estufa de le\u00f1a y paneles solares para un confort durante todo el a\u00f1o<\/li>\n<li>Sistema de alarma, dep\u00f3sito de agua y cochera para mayor practicidad y seguridad<\/li>\n<\/ul>"],"houzez_total_property_views":["123"],"houzez_views_by_date":["a:61:{s:10:\"02-12-2026\";i:1;s:10:\"02-14-2026\";i:1;s:10:\"02-15-2026\";i:4;s:10:\"02-17-2026\";i:1;s:10:\"02-18-2026\";i:1;s:10:\"02-20-2026\";i:1;s:10:\"02-22-2026\";i:1;s:10:\"02-23-2026\";i:1;s:10:\"02-24-2026\";i:1;s:10:\"02-25-2026\";i:1;s:10:\"02-27-2026\";i:2;s:10:\"03-01-2026\";i:1;s:10:\"03-03-2026\";i:1;s:10:\"03-04-2026\";i:2;s:10:\"03-06-2026\";i:2;s:10:\"03-07-2026\";i:1;s:10:\"03-08-2026\";i:3;s:10:\"03-09-2026\";i:1;s:10:\"03-10-2026\";i:2;s:10:\"03-11-2026\";i:3;s:10:\"03-13-2026\";i:3;s:10:\"03-14-2026\";i:1;s:10:\"03-15-2026\";i:2;s:10:\"03-17-2026\";i:1;s:10:\"03-18-2026\";i:1;s:10:\"03-20-2026\";i:1;s:10:\"03-21-2026\";i:1;s:10:\"03-22-2026\";i:2;s:10:\"03-23-2026\";i:2;s:10:\"03-24-2026\";i:2;s:10:\"03-25-2026\";i:1;s:10:\"03-26-2026\";i:1;s:10:\"03-27-2026\";i:3;s:10:\"03-29-2026\";i:1;s:10:\"03-31-2026\";i:1;s:10:\"04-01-2026\";i:3;s:10:\"04-02-2026\";i:3;s:10:\"04-03-2026\";i:3;s:10:\"04-04-2026\";i:1;s:10:\"04-05-2026\";i:1;s:10:\"04-06-2026\";i:2;s:10:\"04-08-2026\";i:2;s:10:\"04-10-2026\";i:1;s:10:\"04-11-2026\";i:1;s:10:\"04-13-2026\";i:1;s:10:\"04-14-2026\";i:1;s:10:\"04-17-2026\";i:3;s:10:\"04-18-2026\";i:1;s:10:\"04-19-2026\";i:2;s:10:\"04-21-2026\";i:1;s:10:\"04-22-2026\";i:2;s:10:\"04-23-2026\";i:1;s:10:\"04-24-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"04-27-2026\";i:2;s:10:\"05-01-2026\";i:2;s:10:\"05-08-2026\";i:3;s:10:\"05-09-2026\";i:1;s:10:\"05-11-2026\";i:1;s:10:\"05-12-2026\";i:2;s:10:\"05-13-2026\";i:2;}"],"houzez_recently_viewed":["2026-05-13 19:27:48"],"fave_property_images":["a:29:{i:0;i:29422;i:1;i:29518;i:2;i:29519;i:3;i:29520;i:4;i:29521;i:5;i:29522;i:6;i:29523;i:7;i:29524;i:8;i:29525;i:9;i:29526;i:10;i:29527;i:11;i:29528;i:12;i:29529;i:13;i:29530;i:14;i:29531;i:15;i:29617;i:16;i:29618;i:17;i:29619;i:18;i:29620;i:19;i:29621;i:20;i:29622;i:21;i:29623;i:22;i:29624;i:23;i:29625;i:24;i:29626;i:25;i:29627;i:26;i:29628;i:27;i:29629;i:28;i:29731;}"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Can Agust\u00edn - Desto<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Can Agust\u00edn - Desto\" \/>\n<meta property=\"og:description\" content=\"Villa San Agust\u00edn es una propiedad recientemente renovada, ubicada en las tranquilas colinas de San Agust\u00edn, que ofrece total privacidad e impresionantes vistas panor\u00e1micas del paisaje verde, las monta\u00f1as y una vista lateral al mar. La villa cuenta con 259 m\u00b2 de espacio habitable en una parcela de 2.034 m\u00b2, con cuatro dormitorios, cuatro ba\u00f1os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desto.life\/es\/propiedad\/can-agustin\/\" \/>\n<meta property=\"og:site_name\" content=\"Desto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Desto\/100066478405366\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T14:27:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desto.life\/wp-content\/uploads\/2025\/12\/29HOUSE_PHOTOSHOOT-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/\",\"url\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/\",\"name\":\"Can Agust\u00edn - Desto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desto.life\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/29HOUSE_PHOTOSHOOT-1-scaled.jpg\",\"datePublished\":\"2025-12-26T09:29:47+00:00\",\"dateModified\":\"2026-01-27T14:27:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/desto.life\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/29HOUSE_PHOTOSHOOT-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/desto.life\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/29HOUSE_PHOTOSHOOT-1-scaled.jpg\",\"width\":2560,\"height\":1705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/can-agustin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/desto.life\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/desto.life\\\/es\\\/propiedad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Can Agust\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/desto.life\\\/es\\\/\",\"name\":\"Desto\",\"description\":\"Real Estate and yatching\",\"publisher\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desto.life\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#organization\",\"name\":\"Desto\",\"url\":\"https:\\\/\\\/desto.life\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desto.life\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_desto.png\",\"contentUrl\":\"https:\\\/\\\/desto.life\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo_desto.png\",\"width\":168,\"height\":47,\"caption\":\"Desto\"},\"image\":{\"@id\":\"https:\\\/\\\/desto.life\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Desto\\\/100066478405366\\\/\",\"https:\\\/\\\/www.instagram.com\\\/desto.life\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Can Agust\u00edn - Desto","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Can Agust\u00edn - Desto","og_description":"Villa San Agust\u00edn es una propiedad recientemente renovada, ubicada en las tranquilas colinas de San Agust\u00edn, que ofrece total privacidad e impresionantes vistas panor\u00e1micas del paisaje verde, las monta\u00f1as y una vista lateral al mar. La villa cuenta con 259 m\u00b2 de espacio habitable en una parcela de 2.034 m\u00b2, con cuatro dormitorios, cuatro ba\u00f1os [&hellip;]","og_url":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/","og_site_name":"Desto","article_publisher":"https:\/\/www.facebook.com\/people\/Desto\/100066478405366\/","article_modified_time":"2026-01-27T14:27:13+00:00","og_image":[{"url":"https:\/\/desto.life\/wp-content\/uploads\/2025\/12\/29HOUSE_PHOTOSHOOT-1-scaled.jpg","width":1024,"height":682,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/","url":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/","name":"Can Agust\u00edn - Desto","isPartOf":{"@id":"https:\/\/desto.life\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/#primaryimage"},"image":{"@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/#primaryimage"},"thumbnailUrl":"https:\/\/desto.life\/wp-content\/uploads\/2025\/12\/29HOUSE_PHOTOSHOOT-1-scaled.jpg","datePublished":"2025-12-26T09:29:47+00:00","dateModified":"2026-01-27T14:27:13+00:00","breadcrumb":{"@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desto.life\/es\/propiedad\/can-agustin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/#primaryimage","url":"https:\/\/desto.life\/wp-content\/uploads\/2025\/12\/29HOUSE_PHOTOSHOOT-1-scaled.jpg","contentUrl":"https:\/\/desto.life\/wp-content\/uploads\/2025\/12\/29HOUSE_PHOTOSHOOT-1-scaled.jpg","width":2560,"height":1705},{"@type":"BreadcrumbList","@id":"https:\/\/desto.life\/es\/propiedad\/can-agustin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/desto.life\/es\/"},{"@type":"ListItem","position":2,"name":"Propiedades","item":"https:\/\/desto.life\/es\/propiedad\/"},{"@type":"ListItem","position":3,"name":"Can Agust\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/desto.life\/es\/#website","url":"https:\/\/desto.life\/es\/","name":"Desto","description":"Real Estate and yatching","publisher":{"@id":"https:\/\/desto.life\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desto.life\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/desto.life\/es\/#organization","name":"Desto","url":"https:\/\/desto.life\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/desto.life\/es\/#\/schema\/logo\/image\/","url":"https:\/\/desto.life\/wp-content\/uploads\/2025\/10\/logo_desto.png","contentUrl":"https:\/\/desto.life\/wp-content\/uploads\/2025\/10\/logo_desto.png","width":168,"height":47,"caption":"Desto"},"image":{"@id":"https:\/\/desto.life\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Desto\/100066478405366\/","https:\/\/www.instagram.com\/desto.life\/"]}]}},"_links":{"self":[{"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/properties\/31045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/properties\/31045\/revisions"}],"predecessor-version":[{"id":32153,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/properties\/31045\/revisions\/32153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/media\/31047"}],"wp:attachment":[{"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/media?parent=31045"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_type?post=31045"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_status?post=31045"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_feature?post=31045"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_label?post=31045"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_country?post=31045"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/desto.life\/es\/wp-json\/wp\/v2\/property_area?post=31045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}